{"id":12364,"date":"2023-09-20T08:14:31","date_gmt":"2023-09-20T01:14:31","guid":{"rendered":"https:\/\/www.sci.ku.ac.th\/web2019\/?post_type=news&#038;p=12364"},"modified":"2023-09-20T08:14:41","modified_gmt":"2023-09-20T01:14:41","slug":"12364-2","status":"publish","type":"news","link":"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/","title":{"rendered":"\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d \u0e19\u0e34\u0e2a\u0e34\u0e15\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23  RESKILL \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 &#8220;\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 Ion Chromatography&#8221;"},"content":{"rendered":"<p>\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d \u0e19\u0e34\u0e2a\u0e34\u0e15\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23<\/p>\n<p>RESKILL \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07<br \/>\n&#8220;\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 Ion Chromatography&#8221;<\/p>\n<p>\u0e2d\u0e1a\u0e23\u0e21\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2566<\/p>\n<p>\u0e08\u0e33\u0e19\u0e27\u0e19\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23<br \/>\n\u0e20\u0e32\u0e04\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 80 \u0e04\u0e19<br \/>\n\u0e20\u0e32\u0e04\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 20 \u0e04\u0e19<\/p>\n<p>\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21<br \/>\n\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e27\u0e35 \u0e0d\u0e32\u0e13\u0e2a\u0e38\u0e04\u0e19\u0e18\u0e4c \u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<br \/>\n&#8211; \u0e20\u0e32\u0e04\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22: \u0e2b\u0e49\u0e2d\u0e07 202<br \/>\n&#8211; \u0e20\u0e32\u0e04\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 : \u0e2b\u0e49\u0e2d\u0e07 1007<\/p>\n<p>QR CODE \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19<br \/>\n<a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=6jIYjG2pPkG_fZ_k1gjgCwTaLhSSDi5PhWNgj9Yq8uxUOEQ2UUZBRktCSjZEM1g2RjNQQUxQVjlDSy4u&amp;qrcode=true\">https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=6jIYjG2pPkG_fZ_k1gjgCwTaLhSSDi5PhWNgj9Yq8uxUOEQ2UUZBRktCSjZEM1g2RjNQQUxQVjlDSy4u&amp;qrcode=true<\/a><\/p>\n<p>\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21: 02-562 5555 \u0e15\u0e48\u0e2d 646155<br \/>\nEMAIL: <a href=\"mailto:fsciequip_center@ku.ac.th\">fsciequip_center@ku.ac.th<\/a><br \/>\nWEB: <a href=\"https:\/\/sci.ku.ac.th\/sec\/\">https:\/\/sci.ku.ac.th\/sec\/<\/a><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-12366\" src=\"https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/uploads\/2023\/09\/RE-01.jpg\" alt=\"\" width=\"1068\" height=\"1500\" srcset=\"https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/uploads\/2023\/09\/RE-01.jpg 1068w, https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/uploads\/2023\/09\/RE-01-214x300.jpg 214w, https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/uploads\/2023\/09\/RE-01-729x1024.jpg 729w, https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/uploads\/2023\/09\/RE-01-768x1079.jpg 768w, https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/uploads\/2023\/09\/RE-01-85x120.jpg 85w\" sizes=\"(max-width: 1068px) 100vw, 1068px\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_12364\" class=\"pvc_stats all  \" data-element-id=\"12364\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" src=\"https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/plugins\/page-views-count\/ajax-loader.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"featured_media":12365,"parent":0,"template":"","meta":{"ngg_post_thumbnail":0},"tags":[],"news_cate":[112],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d \u0e19\u0e34\u0e2a\u0e34\u0e15\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 RESKILL \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 &quot;\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 Ion Chromatography&quot; - \u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\" \/>\n<meta property=\"og:description\" content=\"\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d \u0e19\u0e34\u0e2a\u0e34\u0e15\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 RESKILL \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 &#8220;\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 Ion Chromatography&#8221; \u0e2d\u0e1a\u0e23\u0e21\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2566 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23 \u0e20\u0e32\u0e04\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 80 \u0e04\u0e19 \u0e20\u0e32\u0e04\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 20 \u0e04\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e27\u0e35 \u0e0d\u0e32\u0e13\u0e2a\u0e38\u0e04\u0e19\u0e18\u0e4c \u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c &#8211; \u0e20\u0e32\u0e04\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22: \u0e2b\u0e49\u0e2d\u0e07 202 &#8211; \u0e20\u0e32\u0e04\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 : \u0e2b\u0e49\u0e2d\u0e07 1007 QR CODE \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=6jIYjG2pPkG_fZ_k1gjgCwTaLhSSDi5PhWNgj9Yq8uxUOEQ2UUZBRktCSjZEM1g2RjNQQUxQVjlDSy4u&amp;qrcode=true \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21: 02-562 5555 \u0e15\u0e48\u0e2d 646155 EMAIL: fsciequip_center@ku.ac.th WEB: https:\/\/sci.ku.ac.th\/sec\/\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-20T01:14:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/uploads\/2023\/09\/RE-02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sci.ku.ac.th\/web2019\/#website\",\"url\":\"https:\/\/www.sci.ku.ac.th\/web2019\/\",\"name\":\"\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\",\"description\":\"\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sci.ku.ac.th\/web2019\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/uploads\/2023\/09\/RE-02.jpg\",\"contentUrl\":\"https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/uploads\/2023\/09\/RE-02.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/#webpage\",\"url\":\"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/\",\"name\":\"\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d \u0e19\u0e34\u0e2a\u0e34\u0e15\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 RESKILL \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 \\\"\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 Ion Chromatography\\\" - \u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\",\"isPartOf\":{\"@id\":\"https:\/\/www.sci.ku.ac.th\/web2019\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/#primaryimage\"},\"datePublished\":\"2023-09-20T01:14:31+00:00\",\"dateModified\":\"2023-09-20T01:14:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sci.ku.ac.th\/web2019\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\",\"item\":\"https:\/\/www.sci.ku.ac.th\/web2019\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d \u0e19\u0e34\u0e2a\u0e34\u0e15\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 RESKILL \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 &#8220;\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 Ion Chromatography&#8221;\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/","og_locale":"en_US","og_type":"article","og_title":"\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d \u0e19\u0e34\u0e2a\u0e34\u0e15\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 RESKILL \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 \"\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 Ion Chromatography\" - \u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","og_description":"\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d \u0e19\u0e34\u0e2a\u0e34\u0e15\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 RESKILL \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 &#8220;\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 Ion Chromatography&#8221; \u0e2d\u0e1a\u0e23\u0e21\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2566 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23 \u0e20\u0e32\u0e04\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 80 \u0e04\u0e19 \u0e20\u0e32\u0e04\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 20 \u0e04\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e27\u0e35 \u0e0d\u0e32\u0e13\u0e2a\u0e38\u0e04\u0e19\u0e18\u0e4c \u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c &#8211; \u0e20\u0e32\u0e04\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22: \u0e2b\u0e49\u0e2d\u0e07 202 &#8211; \u0e20\u0e32\u0e04\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 : \u0e2b\u0e49\u0e2d\u0e07 1007 QR CODE \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=6jIYjG2pPkG_fZ_k1gjgCwTaLhSSDi5PhWNgj9Yq8uxUOEQ2UUZBRktCSjZEM1g2RjNQQUxQVjlDSy4u&amp;qrcode=true \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21: 02-562 5555 \u0e15\u0e48\u0e2d 646155 EMAIL: fsciequip_center@ku.ac.th WEB: https:\/\/sci.ku.ac.th\/sec\/","og_url":"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/","og_site_name":"\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","article_modified_time":"2023-09-20T01:14:41+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/uploads\/2023\/09\/RE-02.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.sci.ku.ac.th\/web2019\/#website","url":"https:\/\/www.sci.ku.ac.th\/web2019\/","name":"\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","description":"\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sci.ku.ac.th\/web2019\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/#primaryimage","inLanguage":"en-US","url":"https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/uploads\/2023\/09\/RE-02.jpg","contentUrl":"https:\/\/www.sci.ku.ac.th\/web2019\/wp-content\/uploads\/2023\/09\/RE-02.jpg","width":1500,"height":1000},{"@type":"WebPage","@id":"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/#webpage","url":"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/","name":"\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d \u0e19\u0e34\u0e2a\u0e34\u0e15\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 RESKILL \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 \"\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 Ion Chromatography\" - \u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","isPartOf":{"@id":"https:\/\/www.sci.ku.ac.th\/web2019\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/#primaryimage"},"datePublished":"2023-09-20T01:14:31+00:00","dateModified":"2023-09-20T01:14:41+00:00","breadcrumb":{"@id":"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sci.ku.ac.th\/web2019\/news\/12364-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sci.ku.ac.th\/web2019\/"},{"@type":"ListItem","position":2,"name":"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23","item":"https:\/\/www.sci.ku.ac.th\/web2019\/news\/"},{"@type":"ListItem","position":3,"name":"\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d \u0e19\u0e34\u0e2a\u0e34\u0e15\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 RESKILL \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 &#8220;\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 Ion Chromatography&#8221;"}]}]}},"_links":{"self":[{"href":"https:\/\/www.sci.ku.ac.th\/web2019\/wp-json\/wp\/v2\/news\/12364"}],"collection":[{"href":"https:\/\/www.sci.ku.ac.th\/web2019\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.sci.ku.ac.th\/web2019\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sci.ku.ac.th\/web2019\/wp-json\/wp\/v2\/media\/12365"}],"wp:attachment":[{"href":"https:\/\/www.sci.ku.ac.th\/web2019\/wp-json\/wp\/v2\/media?parent=12364"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sci.ku.ac.th\/web2019\/wp-json\/wp\/v2\/tags?post=12364"},{"taxonomy":"news_cate","embeddable":true,"href":"https:\/\/www.sci.ku.ac.th\/web2019\/wp-json\/wp\/v2\/news_cate?post=12364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}